{"id":7292,"date":"2021-12-02T15:11:10","date_gmt":"2021-12-02T15:11:10","guid":{"rendered":"https:\/\/www.conferenciaepiscopal.pt\/v1\/?p=7292"},"modified":"2021-12-02T16:39:32","modified_gmt":"2021-12-02T16:39:32","slug":"comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio","status":"publish","type":"post","link":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/","title":{"rendered":"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d"},"content":{"rendered":"<p><!--more--><\/p>\n<p>\u201cA hist\u00f3ria secular da inf\u00e2ncia \u00e9 um longo pesadelo do qual s\u00f3 h\u00e1 muito pouco tempo acabamos de acordar\u201d, escreveu Lloyd de Mause, Director do Institute for the Psycho History\u201d (New York) no seu livro\u201cThe History of Childhood\u201d.<\/p>\n<p>O contexto hist\u00f3rico da defini\u00e7\u00e3o de inf\u00e2ncia e ainda mais da adolesc\u00eancia, tal como o concebemos hoje em dia tem, na realidade, poucas dezenas de anos, sendo que os maiores avan\u00e7os nessa \u00e1rea apenas se registaram de forma clara a partir da segunda metade do s\u00e9culo XX.<\/p>\n<p>O mesmo aconteceu, de modo geral, com a pr\u00f3pria vis\u00e3o social do tema e respetivo empenhamento dos governos de diversos pa\u00edses do mundo, quando assinaram a \u201cConven\u00e7\u00e3o dos Direitos das Crian\u00e7as\u201d h\u00e1 bem pouco mais de 30 anos atr\u00e1s.<\/p>\n<p>Hoje em dia, no que diz respeito \u00e0 prote\u00e7\u00e3o das crian\u00e7as, tudo mudou para melhor e ainda bem. Reconhecemos a inf\u00e2ncia dentro de um espectro et\u00e1rio que vai desde o nascimento at\u00e9 aos 18 anos de idade. Sabemos bem da import\u00e2ncia de todas as experi\u00eancias emocionais precoces para o desenvolvimento da estrutura de personalidade dos diferentes adultos, tal como entendemos sem qualquer d\u00favida o peso que determinadas viv\u00eancias traum\u00e1ticas acarretam para cada um, individualmente, e para a forma do seu relacionamento futuro com os outros e com a sociedade em geral.<\/p>\n<p>Dentro destas viv\u00eancias negativas, t\u00eam amplo destaque todas aquelas que a crian\u00e7a n\u00e3o pode nem consegue integrar fisicamente (com os seus pr\u00f3prios limites de um \u201ceu\u201d corporal destru\u00eddos) e muito menos psiquicamente, pois a sua capacidade de entendimento e integra\u00e7\u00e3o destas situa\u00e7\u00f5es lhe \u00e9 completamente imposs\u00edvel, definindo-se assim, e desde logo, a pr\u00f3pria no\u00e7\u00e3o de trauma. Tal \u00e9 o que acontece na generalidade dos casos de abuso sexual de menores.<\/p>\n<p>At\u00e9 ao momento presente, o que a quase totalidade dos estudos destaca sobre esta mat\u00e9ria \u00e9 bastante homog\u00e9neo e permite destacar alguns pontos quase sempre constantes:<\/p>\n<p>&#8211; A baixa idade da crian\u00e7a, habitualmente pr\u00e9-adolescente<\/p>\n<p>&#8211; A possibilidade de tanto raparigas como rapazes serem de igual modo afetados (e, no caso da Igreja, com maior representa\u00e7\u00e3o de rapazes como v\u00edtimas)<\/p>\n<p>&#8211; A percentagem muito maior de adultos do sexo masculino enquanto abusadores, comparativamente \u00e0s do sexo feminino<\/p>\n<p>&#8211; A frequ\u00eancia com que os abusos acontecem em espa\u00e7os f\u00edsicos conhecidos pelas pr\u00f3prias crian\u00e7as e perpetrados por adultos da sua rela\u00e7\u00e3o e a quem elas ou os seus familiares mais pr\u00f3ximos depositavam at\u00e9 ent\u00e3o liga\u00e7\u00f5es de confian\u00e7a ou outras.<\/p>\n<p>&#8211; A alta probabilidade dos abusos acontecerem num padr\u00e3o continuado, facto muito mais do que em ato \u00fanico ou isoladamente<\/p>\n<p>&#8211; A facilidade de, por defesa ps\u00edquica, haver por parte da v\u00edtima o que se designa por mecanismo de \u201cidentifica\u00e7\u00e3o ao agressor\u201d, perpetuando-se assim transgeracionalmente este tipo de situa\u00e7\u00e3o (tamb\u00e9m como forma de controlo e poder sobre o outro, que assim se domina e submete)<\/p>\n<p>&#8211; Ainda o facto da passagem do tempo (anos, vulgarmente) ir facilitando defesas ps\u00edquicas perante o trauma vivido, nomeadamente o \u201crecalcamento\u201d e a \u201cclivagem\u201d, tornando cada vez mais dif\u00edcil para cada v\u00edtima a tarefa de ousar falar, romper o sil\u00eancio, libertar-se de um passado maligno que n\u00e3o se apaga nunca. Nunca.<\/p>\n<p>&#8211; O poder de for\u00e7as de coa\u00e7\u00e3o externa (amea\u00e7as ao pr\u00f3prio ou a pessoas a quem se referencia familiarmente) e, sobretudo, de coa\u00e7\u00e3o interna que levam com imensa frequ\u00eancia ao sil\u00eancio que emerge do medo, da vergonha e da culpa, bem como \u00e0 falta de um interlocutor atento, capaz de perceber altera\u00e7\u00f5es (ainda que subliminares) no comportamento e express\u00e3o das emo\u00e7\u00f5es dos mais novos enquanto v\u00edtimas e\/ou quando estas ousam falam, algu\u00e9m que respeite e valorize a sua narrativa e n\u00e3o que a silencie ou, simplesmente, ignore.<\/p>\n<p>&#8211; Disso mesmo surge o que \u00e9 tamb\u00e9m designado por \u201cefeito iceberg\u201d, isto \u00e9, apenas conheceremos sempre uma pequena parte de tudo o que pode ter acontecido na realidade; ou seja, o que por fim emerge de qualquer estudo ou investiga\u00e7\u00e3o nunca \u00e9 tudo, mas sim a parte poss\u00edvel de narrativas de muitos outros que guardam e guardar\u00e3o para sempre experi\u00eancias criminosas das quais foram claramente v\u00edtimas.<\/p>\n<p>Em Portugal, nos \u00faltimos tempos e tal como em diversos pa\u00edses, registou-se uma saud\u00e1vel onda de indigna\u00e7\u00e3o, movida pela procura de uma verdade hist\u00f3rica, sobre o que poder\u00e1 ter acontecido a um n\u00famero incont\u00e1vel de menores no campo dos abusos sexuais em diversos contextos da sociedade, em especial no seio da pr\u00f3pria Igreja Cat\u00f3lica, numa vis\u00e3o que o seu pr\u00f3prio representante m\u00e1ximo, Sua Santidade o Papa Francisco, tem vindo a pedir sucessivamente para ser objeto de clarifica\u00e7\u00e3o inequ\u00edvoca, numa atitude de absoluto reconhecimento da exist\u00eancia destes crimes, pedindo (sic) \u201co fim de uma cultura de morte e silenciamento c\u00famplice\u201d levado a cabo durante d\u00e9cadas por elementos da pr\u00f3pria Igreja.<\/p>\n<p>\u00c9 para isso que aqui estamos, neste momento, a dar in\u00edcio a um trabalho que naturalmente se prev\u00ea complexo, longo, dif\u00edcil de definir quanto a resultados finais, mas que verdadeiramente teria que ser feito, mesmo que ainda assim venha a ser olhado como origem de outros que se lhe possam vir a seguir no futuro, procurando sempre a necessidade de refor\u00e7o de verdadeiras pol\u00edticas de prote\u00e7\u00e3o e promo\u00e7\u00e3o da inf\u00e2ncia e adolesc\u00eancia, contribuindo assim para sociedades mais justas, saud\u00e1veis e livres num futuro melhor que tanto desejamos construir<\/p>\n<p>Esta Comiss\u00e3o que agora se constitui, organiza-se de forma aut\u00f3noma e independente da pr\u00f3pria Igreja cat\u00f3lica, bem como de todo o tipo de outros credos ou religi\u00f5es, ra\u00e7as e etnias, g\u00e9neros e identidades, sendo que os seus membros v\u00e3o atuar exclusivamente no \u00e2mbito das respetivas val\u00eancias profissionais e\/ou representativas de diversas \u00e1reas fins, incluindo a sociedade civil.<\/p>\n<p>A Comiss\u00e3o \u00e9 multidisciplinar, parit\u00e1ria e contar\u00e1 com a presen\u00e7a dos seguintes membros efetivos:<\/p>\n<p>&#8211; Pedro Strecht, M\u00e9dico Pedopsiquiatra (Coordenador)<\/p>\n<p>&#8211; \u00c1lvaro Laborinho L\u00facio, Juiz Conselheiro Jubilado do Supremo Tribunal de Justi\u00e7a, antigo Ministro da Justi\u00e7a, Escritor<\/p>\n<p>&#8211; Ana Nunes de Almeida, Soci\u00f3loga e Investigadora Instituto de Ci\u00eancias Sociais da Universidade de Lisboa e Presidente do respetivo Conselho Cient\u00edfico. Vice-presidente do Conselho Nacional de Sa\u00fade, membro do Conselho Consultivo do IAC e do Conselho de \u00c9tica do Laborat\u00f3rio Pro-Child. Tem desenvolvido pesquisa na \u00e1rea dos maus-tratos a menores, cat\u00e1strofes, crian\u00e7as e animais. Coordenou o estudo sobre Maus Tratos a Crian\u00e7as na Fam\u00edlia, encomendado pela AR em 1999.<\/p>\n<p>&#8211; Daniel Sampaio, Psiquiatra, Professor Catedr\u00e1tico Jubilado da FML; Fundador da Sociedade de Terapia Familiar, autor de dezenas de livros na \u00e1rea da Sa\u00fade Mental, com especial foco na adolesc\u00eancia.<\/p>\n<p>&#8211; Filipa Tavares, Assistente Social e Terapeuta Familiar; trabalhou cerca de 25 anos numa IPSS, Casa da Praia\/Centro Dr. Jo\u00e3o dos Santos com fam\u00edlias disfuncionais e de risco.<\/p>\n<p>&#8211; Catarina Vasconcelos, Cineasta, Licenciada na Faculdade de Belas Artes com p\u00f3s-gradua\u00e7\u00e3o em Antropologia Visual no ISCTE e mestrado no Royal College of Art, Londres<\/p>\n<p>Durante o decurso do tempo de interven\u00e7\u00e3o desta Comiss\u00e3o, podem vir a ser integrados mais profissionais cuja interven\u00e7\u00e3o especializada se revele fundamental em diversas etapas do trabalho a realizar.<\/p>\n<p>A Comiss\u00e3o definir\u00e1 o seu tempo e m\u00e9todo de atua\u00e7\u00e3o, com recolha e tratamento de depoimentos, informa\u00e7\u00e3o documental e outros dados de relevo obtidos atrav\u00e9s de metodologias distintas, bem como elabora\u00e7\u00e3o e apresenta\u00e7\u00e3o p\u00fablica de um Relat\u00f3rio, balizando-o durante o ano civil de 2022 (de janeiro a dezembro), salvo o surgimento de condicionantes de exce\u00e7\u00e3o que poder\u00e3o vir a ditar o alargamento deste prazo.<\/p>\n<p>Relembra, desde j\u00e1, que o encorajamento para depoimento das v\u00edtimas requer um habitualmente longo tempo de espera e conquista de confian\u00e7a para que estas sintam que a sua palavra \u00e9 importante para relatar experi\u00eancias traum\u00e1ticas das suas vidas passadas, minorando ainda agora danos psicossociais importantes, tal como sentimentos comuns de zanga, raiva e, sobretudo de desprote\u00e7\u00e3o e injusti\u00e7a face a membros a Igreja cat\u00f3lica, outros adultos de proximidade e at\u00e9 da sociedade em geral.<\/p>\n<p>Por isso, apelamos desde j\u00e1 a todas e todos quanto possam ter sido v\u00edtimas destes crimes hediondos para que falem. Que relatem, finalmente e sem medo, o que lhes aconteceu. Mesmo perante naturais hesita\u00e7\u00f5es, completamente aceit\u00e1veis diante de situa\u00e7\u00f5es sobre as quais podem ter passado d\u00e9cadas, tocando agora em assuntos que n\u00e3o desejam voltar a fazer emergir, por favor, confiem na vossa voz interior e na utilidade de a partilhar para que nada de semelhante possa continuar a acontecer.<\/p>\n<p>N\u00e3o podemos mudar o passado, mas podemos sempre construir um futuro melhor e livre da repeti\u00e7\u00e3o deste tipo de situa\u00e7\u00e3o junto dos vossos filhos, netos ou simplesmente de todas as crian\u00e7as e adolescentes em que certamente podemos rever partes de n\u00f3s mesmos.<\/p>\n<p>\u00c9 por isso que a Comiss\u00e3o deseja contar com a disponibilidade e o empenho de toda a sociedade civil, toda, nomeadamente daquelas e daqueles que no passado tenham sido alvo de abusos sexuais no seio da Igreja Cat\u00f3lica Portuguesa enquanto menores de idade, seguindo o lema de \u201cDar Voz ao Sil\u00eancio\u201d para \u201cConhecer o Passado, Planear o Futuro\u201d. Para tal, repetimos, garante-se desde logo um absoluto respeito e sigilo pessoal e profissional sobre a hist\u00f3ria de vida traum\u00e1tica de toda e qualquer pessoa que nos venha a contactar.<\/p>\n<p>A Comiss\u00e3o est\u00e1 consciente de que o trabalho que a espera e respetivos resultados finais n\u00e3o t\u00eam qualquer \u201ca priori\u201d e est\u00e3o, de igual modo, dependentes da pr\u00f3pria capacidade colaborativa da Igreja Cat\u00f3lica Portuguesa e ainda de todas as Comiss\u00f5es Diocesanas criadas em Portugal desde 2019 que tanto se t\u00eam empenhado nestes terrenos, com profissionais de \u00e1reas muito diversas, com postura v\u00e1lida e isenta, pedindo que se continuem a empenhar na facilita\u00e7\u00e3o de contactos para pessoas, institui\u00e7\u00f5es ou outros grupos que em todo o Pa\u00eds possam e queiram associar-se transversalmente numa rede de fornecimento de dados para recolha de informa\u00e7\u00e3o de relevo, nem que seja (sic) \u201cimpelidos pela dor e pela vergonha de n\u00e3o terem sido boas guardi\u00e3s dos menores que nos foram confiados\u201d, como tamb\u00e9m escreveu o Papa Francisco.<\/p>\n<p>A Comiss\u00e3o espera o suporte da comunica\u00e7\u00e3o social na eventual referencia\u00e7\u00e3o de situa\u00e7\u00f5es ainda atuais ou do passado, deseja a exist\u00eancia de investiga\u00e7\u00e3o jornal\u00edstica \u00fatil ao tema e divulga\u00e7\u00e3o de canais de contacto que em janeiro ser\u00e3o postos \u00e0 disposi\u00e7\u00e3o de todos quantos queiram reportar o seu passado traum\u00e1tico. As redes sociais oferecem boas oportunidades de acesso a todas as pessoas an\u00f3nimas que deseja ver colaborarem na revela\u00e7\u00e3o deste objeto de estudo, pelo que teremos certamente um contacto telef\u00f3nico dispon\u00edvel, um e-mail para os que preferirem essa forma de contacto e uma p\u00e1gina de internet recordando quem somos e o que fazemos.<\/p>\n<p>A Comiss\u00e3o pede simultaneamente a todos o maior respeito e compreens\u00e3o pela tranquilidade necess\u00e1ria ao bom desempenho do seu trabalho estando prevista para a comunica\u00e7\u00e3o social uma Sess\u00e3o de Apresenta\u00e7\u00e3o da Equipa e defini\u00e7\u00e3o de metodologias e cronograma deste trabalho (j\u00e1 no in\u00edcio do m\u00eas de aneiro, em data a anunciar, mas provavelmente no dia 10 dado o prazo das atuais medidas vigentes em rela\u00e7\u00e3o \u00e0 preven\u00e7\u00e3o da transmiss\u00e3o da Covid 19). Compromete-se a realizar um \u201cbriefing\u201d para ponto de situa\u00e7\u00e3o a meio do tempo definido, tal como far\u00e1 a divulga\u00e7\u00e3o de conclus\u00f5es atrav\u00e9s de um Relat\u00f3rio a apresentar at\u00e9 dezembro de 2022. Quanto ao mais, requer-se recato e sigilo que todos os membros desta Comiss\u00e3o, mas todos mesmo, iremos ter de cumprir.<\/p>\n<p>De facto, tal n\u00e3o poderia ser de outro modo, pois a Comiss\u00e3o garante o total anonimato de todos aqueles que desejem colaborar enquanto v\u00edtimas, na mais sincera empatia pela sua dor e sofrimento, sabendo que cada pessoa \u00e9 realmente importante e, como j\u00e1 afirmamos, a sua voz conta. Mais do que alcan\u00e7ar n\u00fameros, algoritmos ou dados percentuais, procuramos chegar a pessoas e sendo essa uma mais que poss\u00edvel dificuldade ser\u00e1, com certeza, a mais esperada e justa recompensa para todos os que v\u00e3o trabalhar nesta equipa.<\/p>\n<p>A Comiss\u00e3o trabalhar\u00e1 em espa\u00e7o f\u00edsico aut\u00f3nomo, exteriormente descaracterizado e relembra ainda que n\u00e3o se substitui \u00e0s entidades jur\u00eddicas competentes perante a revela\u00e7\u00e3o de casos cujos crimes n\u00e3o se encontrem ainda prescritos (at\u00e9 por este tipo de crime \u00e9 de natureza p\u00fablica e o prazo da sua prescri\u00e7\u00e3o mudou), nem \u00e0s estruturas de sa\u00fade mental existentes em situa\u00e7\u00f5es de manifesta necessidade de apoio emocional.<\/p>\n<p>A Comiss\u00e3o agradece \u00e0 Igreja Cat\u00f3lica Portuguesa, nomeadamente a D. Jos\u00e9 Ornelas enquanto Presidente da Confer\u00eancia Episcopal, que seguindo as orienta\u00e7\u00f5es ditadas por Sua Santidade o Papa Francisco, depositou uma total confian\u00e7a face a constitui\u00e7\u00e3o desta Equipa, bem como a disponibilidade de facilitar os meios necess\u00e1rios ao seu trabalho com isen\u00e7\u00e3o e independ\u00eancia, raz\u00e3o porque todos aceitamos fazer parte do risco deste tremendo desafio.<\/p>\n<p>Por \u00faltimo, atrav\u00e9s do trabalho que se iniciar\u00e1 em janeiro de 2022, a Comiss\u00e3o espera tamb\u00e9m vir a dar o seu contributo alargado para a consolida\u00e7\u00e3o futura da promo\u00e7\u00e3o e prote\u00e7\u00e3o de todos os menores de idade, conforme o descrito na Conven\u00e7\u00e3o Universal dos Direitos das Crian\u00e7as. Assim tenhamos n\u00f3s o necess\u00e1rio engenho e arte, contando sempre e genuinamente com aquelas e aqueles que por bem queiram manter viva a sua atitude cr\u00edtica em rela\u00e7\u00e3o ao nosso desempenho profissional, fazendo-a chegar atrav\u00e9s de coment\u00e1rios, sugest\u00f5es, factos ou ideias \u00fateis ao longo deste processo de que, afinal, todos podemos fazer parte.<\/p>\n<p>Muito obrigado!<\/p>\n<p>Pedro Strecht<\/p>\n<p>Lisboa, 2 de dezembro de 2021<\/p>\n<p><a href=\"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/20211202_Coordenador-CIEAMI-GULBENKIAN.pdf\" target=\"_blank\" rel=\"noopener\">[PDF]<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":7299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[74,4],"tags":[],"class_list":["post-7292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrada","category-documentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d - Confer\u00eancia Episcopal Portuguesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d - Confer\u00eancia Episcopal Portuguesa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/\" \/>\n<meta property=\"og:site_name\" content=\"Confer\u00eancia Episcopal Portuguesa\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T15:11:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T16:39:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/comissao-nacional4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manuel Costa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Costa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/\"},\"author\":{\"name\":\"Manuel Costa\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#\\\/schema\\\/person\\\/ab696457f75fe8e22b00183bfacb4cb2\"},\"headline\":\"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d\",\"datePublished\":\"2021-12-02T15:11:10+00:00\",\"dateModified\":\"2021-12-02T16:39:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/\"},\"wordCount\":2433,\"publisher\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/wp-content\\\/uploads\\\/comissao-nacional4.jpg\",\"articleSection\":[\"#entrada\",\"Documentos\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/\",\"url\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/\",\"name\":\"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d - Confer\u00eancia Episcopal Portuguesa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/wp-content\\\/uploads\\\/comissao-nacional4.jpg\",\"datePublished\":\"2021-12-02T15:11:10+00:00\",\"dateModified\":\"2021-12-02T16:39:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/wp-content\\\/uploads\\\/comissao-nacional4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/wp-content\\\/uploads\\\/comissao-nacional4.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#website\",\"url\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/\",\"name\":\"Confer\u00eancia Episcopal Portuguesa\",\"description\":\"Igreja Cat\u00f3lica em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#organization\",\"name\":\"Confer\u00eancia Episcopal Portuguesa\",\"url\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/wp-content\\\/uploads\\\/cropped-logoTransparente.png\",\"contentUrl\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/wp-content\\\/uploads\\\/cropped-logoTransparente.png\",\"width\":512,\"height\":512,\"caption\":\"Confer\u00eancia Episcopal Portuguesa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.conferenciaepiscopal.pt\\\/v1\\\/#\\\/schema\\\/person\\\/ab696457f75fe8e22b00183bfacb4cb2\",\"name\":\"Manuel Costa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5054571ff5d2454cd50657fc4e61d0c32d7a5d0d3b36ef6c0f6e269276d13618?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5054571ff5d2454cd50657fc4e61d0c32d7a5d0d3b36ef6c0f6e269276d13618?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5054571ff5d2454cd50657fc4e61d0c32d7a5d0d3b36ef6c0f6e269276d13618?s=96&d=mm&r=g\",\"caption\":\"Manuel Costa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d - Confer\u00eancia Episcopal Portuguesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/","og_locale":"pt_PT","og_type":"article","og_title":"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d - Confer\u00eancia Episcopal Portuguesa","og_url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/","og_site_name":"Confer\u00eancia Episcopal Portuguesa","article_published_time":"2021-12-02T15:11:10+00:00","article_modified_time":"2021-12-02T16:39:32+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/comissao-nacional4.jpg","type":"image\/jpeg"}],"author":"Manuel Costa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Manuel Costa","Tempo estimado de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#article","isPartOf":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/"},"author":{"name":"Manuel Costa","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#\/schema\/person\/ab696457f75fe8e22b00183bfacb4cb2"},"headline":"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d","datePublished":"2021-12-02T15:11:10+00:00","dateModified":"2021-12-02T16:39:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/"},"wordCount":2433,"publisher":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#organization"},"image":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/comissao-nacional4.jpg","articleSection":["#entrada","Documentos"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/","url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/","name":"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d - Confer\u00eancia Episcopal Portuguesa","isPartOf":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#primaryimage"},"image":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/comissao-nacional4.jpg","datePublished":"2021-12-02T15:11:10+00:00","dateModified":"2021-12-02T16:39:32+00:00","breadcrumb":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#primaryimage","url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/comissao-nacional4.jpg","contentUrl":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/comissao-nacional4.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/comissao-independente-para-o-estudo-de-abusos-sexuais-na-igreja-catolica-portuguesa-dar-voz-ao-silencio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.conferenciaepiscopal.pt\/v1\/"},{"@type":"ListItem","position":2,"name":"Comiss\u00e3o Independente Para o Estudo de Abusos Sexuais na Igreja Cat\u00f3lica Portuguesa: \u201cDar Voz ao Sil\u00eancio\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#website","url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/","name":"Confer\u00eancia Episcopal Portuguesa","description":"Igreja Cat\u00f3lica em Portugal","publisher":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conferenciaepiscopal.pt\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#organization","name":"Confer\u00eancia Episcopal Portuguesa","url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/cropped-logoTransparente.png","contentUrl":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-content\/uploads\/cropped-logoTransparente.png","width":512,"height":512,"caption":"Confer\u00eancia Episcopal Portuguesa"},"image":{"@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conferenciaepiscopal.pt\/v1\/#\/schema\/person\/ab696457f75fe8e22b00183bfacb4cb2","name":"Manuel Costa","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/5054571ff5d2454cd50657fc4e61d0c32d7a5d0d3b36ef6c0f6e269276d13618?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5054571ff5d2454cd50657fc4e61d0c32d7a5d0d3b36ef6c0f6e269276d13618?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5054571ff5d2454cd50657fc4e61d0c32d7a5d0d3b36ef6c0f6e269276d13618?s=96&d=mm&r=g","caption":"Manuel Costa"}}]}},"_links":{"self":[{"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/posts\/7292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/comments?post=7292"}],"version-history":[{"count":3,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/posts\/7292\/revisions"}],"predecessor-version":[{"id":7296,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/posts\/7292\/revisions\/7296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/media\/7299"}],"wp:attachment":[{"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/media?parent=7292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/categories?post=7292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conferenciaepiscopal.pt\/v1\/wp-json\/wp\/v2\/tags?post=7292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}